{"id":96652,"date":"2019-02-22T11:21:57","date_gmt":"2019-02-22T10:21:57","guid":{"rendered":"https:\/\/clinical.r-biopharm.com\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/"},"modified":"2019-08-06T14:52:41","modified_gmt":"2019-08-06T12:52:41","slug":"gastroenteritis-diese-viren-sollten-sie-im-blick-haben","status":"publish","type":"post","link":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/","title":{"rendered":"Gastroenteritis: Diese Viren sollten Sie im Blick haben"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8220;.vc_custom_1550828691404{margin-bottom: 0px !important;}&#8220;]<strong>Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind es Viren, die f\u00fcr die Infektionen verantwortlich sind.<\/strong><!--more--><\/p>\n<p>Die akute Gastroenteritis ist eine der Hauptursachen von Morbidit\u00e4t und Mortalit\u00e4t auf der Welt. Es wird gesch\u00e4tzt, dass weltweit rund 1,5 Millionen Kinder unter 5 Jahren an Diarrhoe sterben \u2013 mehr als an AIDS, Malaria und Masern zusammen. In den meisten F\u00e4llen wird die Erkrankung von Viren verursacht, weniger h\u00e4ufig von Bakterien oder Parasiten. Mehrere Studien zeigen, dass Noroviren f\u00fcr fast 50 % der weltweiten Gastroenteritisausbr\u00fcche verantwortlich sind. Das hochansteckende Virus verursacht vor allem in den Wintermonaten oft gro\u00dfe Epidemien in Gemeinschaftseinrichtungen wie Krankenh\u00e4usern oder Seniorenheimen. Rotaviren sind trotz der Einf\u00fchrung eines Impfstoffes immer noch der h\u00e4ufigste Erreger von schwerer Diarrh\u00f6e bei Kindern unter 5 Jahren. Adenoviren sind die dritth\u00e4ufigste Ursache f\u00fcr virale Gastroenteritis bei Kindern. In der Praxis k\u00f6nnen h\u00e4ufig Mischinfektionen mit zwei oder mehr Gastroenteritis-Erregern beobachtet werden, beispielsweise mit Rotavirus und Norovirus.[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1550829059988{margin-bottom: 0px !important;}&#8220;]\n<h3>Wann ist ein Erreger-Nachweis erforderlich?<\/h3>\n<p>Aufgrund der typischen Symptome ist eine Gastroenteritis gut zu diagnostizieren. Dennoch sollte der \u00a0Erregernachweis in folgenden F\u00e4llen durchgef\u00fchrt werden:[\/vc_column_text][mk_custom_list style=&#8220;mk-moon-circle-small&#8220;]\n<ul>\n<li>bei schweren Krankheitsverl\u00e4ufen, z.B. mit blutigem Stuhl, hohem Fieber oder Dehydrierung<\/li>\n<li>bei immungeschw\u00e4chten Personen<\/li>\n<li>bei station\u00e4rem Aufenthalt und nosokomialen Ausbr\u00fcchen<\/li>\n<li>bei Komorbidit\u00e4ten<\/li>\n<li>bei einem vorangegangenen Auslandsaufenthalt<\/li>\n<li>bei einer vorangegangenen Antibiotikatherapie<\/li>\n<li>wenn der Verdacht auf eine meldepflichtige Infektion besteht<\/li>\n<\/ul>\n[\/mk_custom_list][vc_column_text css=&#8220;.vc_custom_1550829082884{margin-bottom: 0px !important;}&#8220;]\n<h3>In welchen F\u00e4llen besteht Meldepflicht?<\/h3>\n<p>Um eine unkontrollierte Ausbreitung zu verhindern, besteht nach dem deutschen Infektionsschutzgesetz (<a href=\"http:\/\/www.gesetze-im-internet.de\/ifsg\/__6.html\" target=\"_blank\" rel=\"noopener noreferrer\">IfSG \u00a7 6 para. 1 no. 2<\/a>) eine Meldepflicht f\u00fcr Rotavirus, Norovirus sowie einige bakterielle Gastroenteritis-Erreger. Demnach ist bereits der Verdacht auf eine akute infekti\u00f6se Gastroenteritis meldepflichtig, wenn[\/vc_column_text][mk_custom_list style=&#8220;mk-moon-circle-small&#8220;]\n<ul>\n<li>die betroffene Person Umgang mit Lebensmitteln hat oder in Gemeinschaftseinrichtungen besch\u00e4ftigt ist, oder<\/li>\n<li>zwei oder mehr gleichartige Erkrankungen auftreten, bei denen ein epidemischer Zusammenhang m\u00f6glich ist.<\/li>\n<\/ul>\n[\/mk_custom_list][vc_column_text css=&#8220;.vc_custom_1550830740590{margin-bottom: 0px !important;}&#8220;]\n<h3>Wie wird die Labordiagnostik durchgef\u00fchrt?<\/h3>\n[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;.vc_custom_1550829315942{margin-bottom: 0px !important;}&#8220;]Der spezifische Nachweis der Erreger erfolgt im Labor meist durch Enzymimmunoassays (ELISA) oder real-time PCR-Tests. Es gibt aber auch schnellere Methoden \u2013 wie den Schnelltest <a href=\"https:\/\/clinical.r-biopharm.com\/products\/ridaquick-rota-adeno-noro-combi\/\">RIDA\u00aeQUICK Rota\/Adeno\/Noro Combi<\/a> (Art. Nr. N1903). Dieser qualitative immunchromatografische Lateral Flow-Test erm\u00f6glicht eine Schnellerkennung der drei wichtigsten viralen Gastroenteritis-Erreger in nur 15 Minuten.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][mk_image src=&#8220;https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2018\/03\/2018-03_n1903-rida-quick-rotaadernonoro-combi-mit-certificaten_rgb_lowres.jpg&#8220; link=&#8220;https:\/\/clinical.r-biopharm.com\/products\/ridaquick-rota-adeno-noro-combi\/&#8220; title=&#8220;RIDA\u00aeQUICK Rota\/Adeno\/Noro Combi&#8220; caption_location=&#8220;outside-image&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8220;.vc_custom_1550828691404{margin-bottom: 0px !important;}&#8220;]Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind es Viren, die f\u00fcr die Infektionen verantwortlich sind.<\/p>\n","protected":false},"author":27,"featured_media":96630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[246,257,242],"tags":[],"class_list":["post-96652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastrointestale-infektionen","category-schnelltests","category-virologie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gastroenteritis: Diese Viren sollten Sie im Blick haben - Clinical Diagnostics<\/title>\n<meta name=\"description\" content=\"Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind Viren verantwortlich.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastroenteritis: Diese Viren sollten Sie im Blick haben - Clinical Diagnostics\" \/>\n<meta property=\"og:description\" content=\"Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind Viren verantwortlich.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/\" \/>\n<meta property=\"og:site_name\" content=\"Clinical Diagnostics\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-22T10:21:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-06T12:52:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2019\/02\/2019-02_news_website_rota-adeno-noro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1438\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Janine Dege\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janine Dege\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/\"},\"author\":{\"name\":\"Janine Dege\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/7bcf9ead36ba80c48ad551e786874e6f\"},\"headline\":\"Gastroenteritis: Diese Viren sollten Sie im Blick haben\",\"datePublished\":\"2019-02-22T10:21:57+00:00\",\"dateModified\":\"2019-08-06T12:52:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/\"},\"wordCount\":510,\"image\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/2019-02_news_website_rota-adeno-noro.jpg\",\"articleSection\":[\"Gastrointestale Infektionen\",\"Schnelltests\",\"Virologie\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/\",\"url\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/\",\"name\":\"Gastroenteritis: Diese Viren sollten Sie im Blick haben - Clinical Diagnostics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/2019-02_news_website_rota-adeno-noro.jpg\",\"datePublished\":\"2019-02-22T10:21:57+00:00\",\"dateModified\":\"2019-08-06T12:52:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/7bcf9ead36ba80c48ad551e786874e6f\"},\"description\":\"Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind Viren verantwortlich.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/2019-02_news_website_rota-adeno-noro.jpg\",\"contentUrl\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/2019-02_news_website_rota-adeno-noro.jpg\",\"width\":1438,\"height\":525,\"caption\":\"viral-gastroenteritis-rota-adeno-noro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/news\\\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastroenteritis: Diese Viren sollten Sie im Blick haben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/\",\"name\":\"Clinical Diagnostics\",\"description\":\"A Division of the R-Biopharm Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/7bcf9ead36ba80c48ad551e786874e6f\",\"name\":\"Janine Dege\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cbca03fc07097934a5058c95fc3b1baaf182a156a174233532f9c3887c50eee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cbca03fc07097934a5058c95fc3b1baaf182a156a174233532f9c3887c50eee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cbca03fc07097934a5058c95fc3b1baaf182a156a174233532f9c3887c50eee?s=96&d=mm&r=g\",\"caption\":\"Janine Dege\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastroenteritis: Diese Viren sollten Sie im Blick haben - Clinical Diagnostics","description":"Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind Viren verantwortlich.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/","og_locale":"de_DE","og_type":"article","og_title":"Gastroenteritis: Diese Viren sollten Sie im Blick haben - Clinical Diagnostics","og_description":"Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind Viren verantwortlich.","og_url":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/","og_site_name":"Clinical Diagnostics","article_published_time":"2019-02-22T10:21:57+00:00","article_modified_time":"2019-08-06T12:52:41+00:00","og_image":[{"width":1438,"height":525,"url":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2019\/02\/2019-02_news_website_rota-adeno-noro.jpg","type":"image\/jpeg"}],"author":"Janine Dege","twitter_misc":{"Verfasst von":"Janine Dege","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/#article","isPartOf":{"@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/"},"author":{"name":"Janine Dege","@id":"https:\/\/clinical.r-biopharm.com\/fr\/#\/schema\/person\/7bcf9ead36ba80c48ad551e786874e6f"},"headline":"Gastroenteritis: Diese Viren sollten Sie im Blick haben","datePublished":"2019-02-22T10:21:57+00:00","dateModified":"2019-08-06T12:52:41+00:00","mainEntityOfPage":{"@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/"},"wordCount":510,"image":{"@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2019\/02\/2019-02_news_website_rota-adeno-noro.jpg","articleSection":["Gastrointestale Infektionen","Schnelltests","Virologie"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/","url":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/","name":"Gastroenteritis: Diese Viren sollten Sie im Blick haben - Clinical Diagnostics","isPartOf":{"@id":"https:\/\/clinical.r-biopharm.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/#primaryimage"},"image":{"@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2019\/02\/2019-02_news_website_rota-adeno-noro.jpg","datePublished":"2019-02-22T10:21:57+00:00","dateModified":"2019-08-06T12:52:41+00:00","author":{"@id":"https:\/\/clinical.r-biopharm.com\/fr\/#\/schema\/person\/7bcf9ead36ba80c48ad551e786874e6f"},"description":"Gastroenteritis, auch bekannt als Magen-Darm-Grippe, ist weltweit eine der h\u00e4ufigsten Erkrankungen beim Menschen. Oft sind Viren verantwortlich.","breadcrumb":{"@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/#primaryimage","url":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2019\/02\/2019-02_news_website_rota-adeno-noro.jpg","contentUrl":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2019\/02\/2019-02_news_website_rota-adeno-noro.jpg","width":1438,"height":525,"caption":"viral-gastroenteritis-rota-adeno-noro"},{"@type":"BreadcrumbList","@id":"https:\/\/clinical.r-biopharm.com\/de\/news\/gastroenteritis-diese-viren-sollten-sie-im-blick-haben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clinical.r-biopharm.com\/de\/"},{"@type":"ListItem","position":2,"name":"Gastroenteritis: Diese Viren sollten Sie im Blick haben"}]},{"@type":"WebSite","@id":"https:\/\/clinical.r-biopharm.com\/fr\/#website","url":"https:\/\/clinical.r-biopharm.com\/fr\/","name":"Clinical Diagnostics","description":"A Division of the R-Biopharm Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinical.r-biopharm.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/clinical.r-biopharm.com\/fr\/#\/schema\/person\/7bcf9ead36ba80c48ad551e786874e6f","name":"Janine Dege","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4cbca03fc07097934a5058c95fc3b1baaf182a156a174233532f9c3887c50eee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cbca03fc07097934a5058c95fc3b1baaf182a156a174233532f9c3887c50eee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cbca03fc07097934a5058c95fc3b1baaf182a156a174233532f9c3887c50eee?s=96&d=mm&r=g","caption":"Janine Dege"}}]}},"_links":{"self":[{"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/posts\/96652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/comments?post=96652"}],"version-history":[{"count":2,"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/posts\/96652\/revisions"}],"predecessor-version":[{"id":98635,"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/posts\/96652\/revisions\/98635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/media\/96630"}],"wp:attachment":[{"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/media?parent=96652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/categories?post=96652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/de\/wp-json\/wp\/v2\/tags?post=96652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}