{"id":173258,"date":"2023-03-07T09:00:00","date_gmt":"2023-03-07T08:00:00","guid":{"rendered":"https:\/\/clinical.r-biopharm.com\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/"},"modified":"2023-04-26T10:15:59","modified_gmt":"2023-04-26T08:15:59","slug":"focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti","status":"publish","type":"post","link":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/","title":{"rendered":"Focus sulla diagnostica fecale: un&#8217;intervista con i nostri esperti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L&#8217;analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni e di cosa prestare attenzione durante l&#8217;uso dei kit rapidi.<\/strong><\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heike e Carlo, grazie per averci dedicato del tempo per questa intervista. Potreste presentarvi brevemente e descrivere il vostro lavoro?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heike: <\/strong>Ciao Wiebke, \u00e8 un piacere per noi. Mi chiamo Heike Calado Duarte e accanto a me c&#8217;\u00e8 il mio team leader Carlo Farah. Lavoriamo entrambi in un gruppo di otto ricercatori per lo sviluppo di test rapidi per la diagnostica clinica. Personalmente, lavoro in R-Biopharm da circa dieci anni e dallo scorso anno sono responsabile come Group Leader Research &amp; Development Lateral Flow Clinical Diagnostics. Ho iniziato la mia carriera professionale con una laurea in biologia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlo: <\/strong>Sono in R-Biopharm da pi\u00f9 di dieci anni. In qualit\u00e0 di team leader, guido un gruppo di quattro ricercatori che lavorano allo sviluppo di test rapidi a flusso laterale. In questo team, lavoriamo principalmente sui parametri clinici per la diagnostica dei patogeni rilevabili in campioni fecali. Sono un biotecnologo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quali sono le cose pi\u00f9 importanti da sapere durante l&#8217;analisi di campioni fecali con un test rapido a flusso laterale?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlo: <\/strong>La sfida principale durante l&#8217;analisi di campioni fecali sono i componenti che possono interferire con l&#8217;esecuzione del test. Un campione fecale ha infatti una composizione molto varia e individuale: contiene molte proteine \u200b\u200be solidi. Questo carico di particelle, particolarmente elevato per i campioni di feci, deve essere ridotto al minimo, in quanto pu\u00f2 portare a risultati non validi a causa dell&#8217;ostruzione della striscia reattiva del kit rapido. Allo stesso tempo, in questi campioni c&#8217;\u00e8 un&#8217;alta concentrazione proteica che pu\u00f2 mascherare gli analiti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heike: <\/strong>Sono d&#8217;accordo con Carlo. I campioni sono critici a causa della loro complessit\u00e0 o delle differenze che si possono riscontrare. Pi\u00f9 \u00e8 complesso il campione, tanto pi\u00f9 impegnativo \u00e8 lo sviluppo del kit. Pu\u00f2 essere molto complesso selezionare i materiali pi\u00f9 appropriati per immettere sul mercato un test ottimale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cosa pu\u00f2 influenzare esattamente un test a flusso laterale eseguito con campioni fecali?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlo: <\/strong>I campioni fecali vengono testati sulla base di una malattia sospetta, quindi nei campioni sono spesso presenti microrganismi, sangue occulto o residui di farmaci. Questi componenti possono influenzare il risultato del test. Pertanto, anche queste variabili devono essere prese in considerazione durante lo sviluppo del test e la scelta dei materiali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una dieta molto ricca di pectina e fibre porta a una consistenza viscida del campione di feci, che complica anche l&#8217;elaborazione dell&#8217;analisi e rende ancora pi\u00f9 importante la miscelazione omogenea del campione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heike: <\/strong>A seconda della dieta e della salute del paziente, la composizione del campione fecali varia. Le interferenze possono dipendere dall&#8217;ampia variet\u00e0 di diete e abitudini nutrizionali, come le diete chetogeniche o ad alto contenuto proteico, dalle singole malattie e dalla storia medica del paziente e dall&#8217;assunzione di farmaci. Dobbiamo considerare tutti questi fattori durante lo sviluppo di un test per garantire prestazioni analitiche ottimali.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\"><strong><strong>Cos&#8217;altro c&#8217;\u00e8 da considerare quando si analizzano campioni fecali?&nbsp;<\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heike: <\/strong>Gli analiti da rilevare cos\u00ec come il campione, che consiste principalmente di materiale biologico, hanno una stabilit\u00e0 limitata. Non tutti gli antigeni sono quindi rilevabili per un lungo periodo di tempo. Pertanto, \u00e8 necessario prestare particolare attenzione al trasporto e alla conservazione del campione. Occorre sempre considerare temperatura, tempo e manipolazione. Nel peggiore dei casi, se il campione non viene maneggiato e conservato con cura, si possono ottenere risultati errati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"577\" height=\"577\" src=\"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview_foto-heike.jpg\" alt=\"Heike Calado Duarte\" class=\"wp-image-172661\" srcset=\"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview_foto-heike.jpg 577w, https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview_foto-heike-300x300.jpg 300w, https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview_foto-heike-150x150.jpg 150w, https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview_foto-heike-60x60.jpg 60w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><figcaption class=\"wp-element-caption\">Heike Calado Duarte<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dal vostro punto di vista, quali campioni sono pi\u00f9 problematici per un test a flusso laterale rapido?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heike: <\/strong>I campioni con particelle e solidi molto grandi sono generalmente i pi\u00f9 problematici. Si intendono campioni di feci solide. La ragione \u00e8 l&#8217;elevato carico di particelle. A causa di ci\u00f2, la concentrazione dell&#8217;antigene \u00e8 molto pi\u00f9 bassa rispetto ai restanti componenti, in quanto vi sono moltissimi elementi nel campione che non portano alcun antigene.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlo: <\/strong>Come dice Heike, la cosa pi\u00f9 difficile per noi ricercatori \u00e8 quando il campione di feci \u00e8 solido. Nella maggior parte dei casi, tuttavia, \u00e8 coinvolta una malattia che porta a una diarrea da acquosa a liquida sintomatica. Anche se ci sono eccezioni, come il rilevamento di <em>Helicobacter pylori<\/em>, un batterio che pu\u00f2 scatenare vari sintomi nello stomaco. Di solito viene rilevato da campioni di feci solide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Come devono essere preparati i campioni fecali solidi per ottenere risultati affidabili?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlo: <\/strong>I campioni di feci solide devono prima essere sciolti nel tampone di diluizione del campione, poich\u00e9 solo i componenti liquidi possono fluire attraverso la striscia del test rapido. Nel caso di campioni di feci solide, bisogna eseguire una miscelazione accurata per poter estrarre gli antigeni. Il campione deve quindi essere il pi\u00f9 omogeneo possibile e bisogna evitare che rimangano frammenti o particelle di grandi dimensioni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quali sono i vostri suggerimenti per i nostri clienti?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlo: <\/strong>Assicurarsi che i campioni fecali siano ben diluiti nel tampone di diluizione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Heike: <\/strong>Dare sempre una breve occhiata anche al campione. Molti fattori che possono causare problemi nell&#8217;applicazione del campione sulla striscia reattiva fanno riferimento al singolo campione. Se qualcosa non funziona, non esitare a contattarci: saremo felici di aiutarti, rispondere alle tue domande e ad affrontare eventuali dubbi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>L&#8217;intervista \u00e8 stata condotta da Wiebke Heine, Product Manager Infectious Diseases presso R-Biopharm<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni e di cosa prestare attenzione durante l&#8217;uso dei kit rapidi. Heike e Carlo, grazie per averci dedicato del tempo per questa intervista. Potreste presentarvi brevemente e [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":172658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"96535,95884,95836,97129,95787,95840","_relevanssi_noindex_reason":"","footnotes":""},"categories":[485,480,470],"tags":[],"class_list":["post-173258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infezioni-gastrointestinali","category-test-rapidi","category-virologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Focus sulla diagnostica fecale. un&#039;intervista con i nostri esperti<\/title>\n<meta name=\"description\" content=\"L&#039;analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Focus sulla diagnostica fecale. un&#039;intervista con i nostri esperti\" \/>\n<meta property=\"og:description\" content=\"L&#039;analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/\" \/>\n<meta property=\"og:site_name\" content=\"Clinical Diagnostics\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-07T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T08:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1938\" \/>\n\t<meta property=\"og:image:height\" content=\"706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RalfRechel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RalfRechel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/\"},\"author\":{\"name\":\"RalfRechel\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/b220bdf72bae67938ba87f282e682ddb\"},\"headline\":\"Focus sulla diagnostica fecale: un&#8217;intervista con i nostri esperti\",\"datePublished\":\"2023-03-07T08:00:00+00:00\",\"dateModified\":\"2023-04-26T08:15:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/\"},\"wordCount\":902,\"image\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023-02_vorlage-news-viren-kampagne_interview.jpg\",\"articleSection\":[\"Infezioni gastrointestinali\",\"Test rapidi\",\"Virologia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/\",\"url\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/\",\"name\":\"Focus sulla diagnostica fecale. un'intervista con i nostri esperti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023-02_vorlage-news-viren-kampagne_interview.jpg\",\"datePublished\":\"2023-03-07T08:00:00+00:00\",\"dateModified\":\"2023-04-26T08:15:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/b220bdf72bae67938ba87f282e682ddb\"},\"description\":\"L'analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023-02_vorlage-news-viren-kampagne_interview.jpg\",\"contentUrl\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023-02_vorlage-news-viren-kampagne_interview.jpg\",\"width\":1938,\"height\":706,\"caption\":\"Interview Virology\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/news\\\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Focus sulla diagnostica fecale: un&#8217;intervista con i nostri esperti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/\",\"name\":\"Clinical Diagnostics\",\"description\":\"A Division of the R-Biopharm Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinical.r-biopharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/b220bdf72bae67938ba87f282e682ddb\",\"name\":\"RalfRechel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b09471782fb6b57a9cf9f676694d1cf670bf5d6c256178907f6529c0ff1996a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b09471782fb6b57a9cf9f676694d1cf670bf5d6c256178907f6529c0ff1996a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b09471782fb6b57a9cf9f676694d1cf670bf5d6c256178907f6529c0ff1996a2?s=96&d=mm&r=g\",\"caption\":\"RalfRechel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Focus sulla diagnostica fecale. un'intervista con i nostri esperti","description":"L'analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/","og_locale":"it_IT","og_type":"article","og_title":"Focus sulla diagnostica fecale. un'intervista con i nostri esperti","og_description":"L'analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni.","og_url":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/","og_site_name":"Clinical Diagnostics","article_published_time":"2023-03-07T08:00:00+00:00","article_modified_time":"2023-04-26T08:15:59+00:00","og_image":[{"width":1938,"height":706,"url":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview.jpg","type":"image\/jpeg"}],"author":"RalfRechel","twitter_misc":{"Written by":"RalfRechel","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/#article","isPartOf":{"@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/"},"author":{"name":"RalfRechel","@id":"https:\/\/clinical.r-biopharm.com\/fr\/#\/schema\/person\/b220bdf72bae67938ba87f282e682ddb"},"headline":"Focus sulla diagnostica fecale: un&#8217;intervista con i nostri esperti","datePublished":"2023-03-07T08:00:00+00:00","dateModified":"2023-04-26T08:15:59+00:00","mainEntityOfPage":{"@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/"},"wordCount":902,"image":{"@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/#primaryimage"},"thumbnailUrl":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview.jpg","articleSection":["Infezioni gastrointestinali","Test rapidi","Virologia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/","url":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/","name":"Focus sulla diagnostica fecale. un'intervista con i nostri esperti","isPartOf":{"@id":"https:\/\/clinical.r-biopharm.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/#primaryimage"},"image":{"@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/#primaryimage"},"thumbnailUrl":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview.jpg","datePublished":"2023-03-07T08:00:00+00:00","dateModified":"2023-04-26T08:15:59+00:00","author":{"@id":"https:\/\/clinical.r-biopharm.com\/fr\/#\/schema\/person\/b220bdf72bae67938ba87f282e682ddb"},"description":"L'analisi dei campioni fecali \u00e8 frequente nella diagnostica clinica. Heike e Carlo del nostro team di ricerca e sviluppo ci parlano delle sfide che si incontrano tutti in giorni.","breadcrumb":{"@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/#primaryimage","url":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview.jpg","contentUrl":"https:\/\/clinical.r-biopharm.com\/wp-content\/uploads\/2023\/03\/2023-02_vorlage-news-viren-kampagne_interview.jpg","width":1938,"height":706,"caption":"Interview Virology"},{"@type":"BreadcrumbList","@id":"https:\/\/clinical.r-biopharm.com\/it\/news\/focus-sulla-diagnostica-fecale-unintervista-con-i-nostri-esperti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clinical.r-biopharm.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Focus sulla diagnostica fecale: un&#8217;intervista con i nostri esperti"}]},{"@type":"WebSite","@id":"https:\/\/clinical.r-biopharm.com\/fr\/#website","url":"https:\/\/clinical.r-biopharm.com\/fr\/","name":"Clinical Diagnostics","description":"A Division of the R-Biopharm Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinical.r-biopharm.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/clinical.r-biopharm.com\/fr\/#\/schema\/person\/b220bdf72bae67938ba87f282e682ddb","name":"RalfRechel","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b09471782fb6b57a9cf9f676694d1cf670bf5d6c256178907f6529c0ff1996a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b09471782fb6b57a9cf9f676694d1cf670bf5d6c256178907f6529c0ff1996a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b09471782fb6b57a9cf9f676694d1cf670bf5d6c256178907f6529c0ff1996a2?s=96&d=mm&r=g","caption":"RalfRechel"}}]}},"_links":{"self":[{"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/173258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/comments?post=173258"}],"version-history":[{"count":2,"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/173258\/revisions"}],"predecessor-version":[{"id":173260,"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/173258\/revisions\/173260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/media\/172658"}],"wp:attachment":[{"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/media?parent=173258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/categories?post=173258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinical.r-biopharm.com\/it\/wp-json\/wp\/v2\/tags?post=173258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}